{"id":5,"date":"2020-01-17T18:49:26","date_gmt":"2020-01-17T17:49:26","guid":{"rendered":"https:\/\/alban-pouchelon.fr\/index.php\/mesmerize\/"},"modified":"2026-01-05T12:20:48","modified_gmt":"2026-01-05T11:20:48","slug":"mesmerize","status":"publish","type":"page","link":"https:\/\/alban-pouchelon.fr\/","title":{"rendered":"Front Page"},"content":{"rendered":"<div  id=\"overlappable-4\" style=\"background-color: #ffffff;\" data-label=\"Overlappable\" data-id=\"overlappable-4\" data-export-id=\"overlappable-4\" data-category=\"overlappable\" class=\"overlappable-4 content-section content-section-spacing\" data-overlap=\"true\">\n<div  class=\"\">\n<div  data-type=\"row\" class=\"row spaced-cols text-center\">\n<div  class=\"col-xs-12 col-sm-4 col-padding col-md-3 \"> <a  data-cp-link=\"1\" href=\"#maison-med\" target=\"_self\" rel=\"noopener noreferrer\"><i  class=\"fa icon shadow-large-black aligncenter color1 fa-hospital-o reverse round large\"><\/i><\/a> <\/p>\n<div  data-type=\"column\" class=\"\">\n<h5  class=\"\">Le cabinet<\/h5>\n<p  class=\"\">Pr\u00e9sentation du cabinet, localisation , fonctionnement<\/p>\n<\/div><\/div>\n<div  class=\"col-xs-12 col-sm-4 col-padding col-md-3 \"> <a  data-cp-link=\"1\" href=\"#permis\" target=\"_self\" rel=\"noopener noreferrer\"><i  class=\"fa icon shadow-large-black aligncenter color1 fa-car reverse round large\"><\/i><\/a> <\/p>\n<div  data-type=\"column\" class=\"\">\n<h5  class=\"\">Visite m\u00e9dicale permis de conduire<\/h5>\n<p  class=\"\">Informations diverses pour les consultations d\u2019aptitude au permis de conduire, hors comission m\u00e9dicale<\/p>\n<\/div><\/div>\n<div  class=\"col-xs-12 col-sm-4 col-padding col-md-3 \"> <a  data-cp-link=\"1\" href=\"#fonctionnement\" target=\"_self\" rel=\"noopener noreferrer\"><i  class=\"fa icon shadow-large-black aligncenter color1 fa-stethoscope reverse round large\"><\/i><\/a> <\/p>\n<div  data-type=\"column\" class=\"\">\n<h5  class=\"\">Infos pratiques<\/h5>\n<p  class=\"\">Horaires du cabinet, urgences<\/p>\n<\/div><\/div>\n<div  class=\"col-xs-12 col-sm-4 col-padding col-md-3\"> <a  data-cp-link=\"1\" href=\"#liens-utiles\" target=\"_self\" rel=\"noopener noreferrer\"><i  class=\"fa icon shadow-large-black aligncenter color1 fa-internet-explorer reverse round large\"><\/i><\/a> <\/p>\n<div  data-type=\"column\" class=\"\">\n<h5  class=\"\">Liens utiles<\/h5>\n<p  class=\"\">Divers liens et adresses \u2026<\/p>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<div  id=\"maison-med\" style=\"background-color: #f5fafd;\" data-label=\"maison med\" data-id=\"about-1\" data-export-id=\"about-1\" data-category=\"about\" class=\"about-1 content-section\">\n<div  class=\"gridContainer\">\n<div  class=\"row text-center\">\n<div  class=\"section-title-col\" data-type=\"column\">\n<h2  class=\"\">\n<br >Maison m\u00e9dicale de Biol<\/h2>\n<h6  class=\"\"><\/h6>\n<h2  class=\"\">situ\u00e9e au 9 place Saint Jean Baptiste 38690 BIOL<\/h2>\n<p  class=\"lead\">Acc\u00e8s handicap\u00e9 et ascenceur<br >5 m\u00e9decins g\u00e9n\u00e9ralistes, infirmi\u00e8res, psychologue<\/p>\n<\/div><\/div>\n<div  class=\"row\">\n<div  class=\"button-holder space-bottom space-bottom-small\" data-type=\"column\"> <\/div>\n<div  class=\"col-xs bottom-xs flexbox image-group-bottom-3-img space-bottom-xs center-xs\"> <img  decoding=\"async\" loading=\"lazy\" class=\"left-img shadow-large-black\" data-size=\"500x300\" src=\"https:\/\/i1.wp.com\/alban-pouchelon.fr\/wp-content\/uploads\/2020\/01\/cropped-cropped-halles-2.jpg?w=3840&amp;ssl=1\" alt=\"\" title=\"cropped-cropped-halles-2.jpg\" width=\"343\" height=\"205\"> <img  decoding=\"async\" loading=\"lazy\" class=\"center-img shadow-large-black\" data-size=\"500x300\" src=\"https:\/\/i1.wp.com\/alban-pouchelon.fr\/wp-content\/uploads\/2020\/01\/cropped-cropped-cab-1-1.jpg?w=3840&amp;ssl=1\" alt=\"\" title=\"cropped-cropped-cab-1-1.jpg\" width=\"412\" height=\"227\"> <img  decoding=\"async\" loading=\"lazy\" class=\"right-img shadow-large-black\" data-size=\"500x300\" src=\"https:\/\/i0.wp.com\/alban-pouchelon.fr\/wp-content\/uploads\/2020\/01\/cropped-cropped-eglise-3.jpg?w=3840&amp;ssl=1\" alt=\"\" title=\"cropped-cropped-eglise-3.jpg\" width=\"343\" height=\"217\"><\/div>\n<\/p><\/div>\n<\/div><\/div>\n<div  id=\"horaires\" style=\"background-color: #f5fafd;\" data-label=\"Horaires\" data-id=\"content-2\" data-export-id=\"content-2\" data-category=\"content\" class=\"content-2 content-section content-section-spacing\">\n<div  class=\"gridContainer\">\n<div  class=\"row middle-xs\">\n<div  class=\"col-sm-5 bg-image shadow-large-black\" data-bg=\"image\" style=\"background-image: url(&quot;https:\/\/alban-pouchelon.fr\/wp-content\/uploads\/2020\/01\/cropped-capsule-1079838_1920-1.jpg&quot;);\"><\/div>\n<div  class=\"col-sm-7 full-col-left-padding full-col-right-padding\">\n<div  class=\"row\">\n<div  data-type=\"column\" class=\"space-bottom-small content-title-col\">\n<h5  class=\"\">\n<br >Horaires du cabinet<\/h5>\n<p  class=\"\">Le cabinet est ouvert du lundi au vendredi de 8h \u00e0 12h et de 14h \u00e0 19h. Le samedi, hors exceptions, le cabinet est aussi ouvert le matin.<br >Une permanence t\u00e9l\u00e9phonique est mise en place le midi<\/p>\n<\/div><\/div>\n<div  class=\"row spaced-cols \" data-type=\"row\">\n<div  class=\"col-xs-6\" data-type=\"column\">\n<h5  class=\"\">En cas d\u2019urgence<\/h5>\n<p  class=\"\">Composez le 15 (SAMU)<\/p>\n<p>Urgences de l\u2019hopital de Bourgoin 04 69 15 70 00<\/p>\n<p>Clinique Saint Vincent de Paul<br \/>\n<br >04 74 43 60 60<\/p>\n<p>Permanence maison des consultants 04 74 93 94 95<\/p>\n<p>SOS M\u00e9decins 8h24h&nbsp; (rue Pixel \u00e0 Bourgoin) 04 74 932 932<\/p>\n<p>Recours m\u00e9dical des Vallons de la Tour (St Clair de La Tour) 04 74 83 50 50<\/p>\n<\/div>\n<div  class=\"col-xs-6\" data-type=\"column\">\n<h5  class=\"\">Autres num\u00e9ros<\/h5>\n<p  class=\"\">114 : num\u00e9ro d\u2019urgence pour les malentendants<br >18 : sapeurs pompiers<br >112 : num\u00e9ro d\u2019appel d\u2019urgence europ\u00e9en<br >17 : police secours\n<\/p>\n<\/div>\n<div  class=\"col-xs-6\" data-type=\"column\">\n<h5  class=\"\">Garde<\/h5>\n<p  class=\"\">de 20h \u00e0 minuit, en semaine,  les samedi 13h-24h et les dimanche 8h-24h vous pouvez consulter \u00e0 la maison m\u00e9dicale de garde \u00e0 l\u2019hopital de Pont de Beauvoisin (Appeler au pr\u00e9alable le 15 ou le 0810153333)<\/p>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<div  id=\"fonctionnement\" style=\"background-color: #ffffff;\" data-label=\"Fonctionnement\" data-id=\"features-12-card-bordered\" data-export-id=\"features-12-card-bordered\" data-category=\"features\" class=\"features-12-card-bordered content-section content-section-spacing \">\n<div  class=\"gridContainer\">\n<div  class=\"row text-center\">\n<div  class=\"section-title-col\" data-type=\"column\">\n<p  class=\"lead\">\n<br >Pr\u00e9cisions sur le fonctionnement des consultations<\/p>\n<\/div><\/div>\n<div  class=\"row spaced-cols\" data-type=\"row\">\n<div  class=\"col-sm-6\">\n<div  class=\"card row-card bordered y-move\">\n<div  class=\"row\">\n<div  class=\"col-sm-fit icon-column\"> <i  class=\"fa icon fa-connectdevelop round bordered color2\"><\/i> <\/div>\n<div  class=\"col-sm\" data-type=\"column\">\n<h5  class=\"color2\">Les consultations sont sur rendez-vous<\/h5>\n<p  class=\"\">Le temps r\u00e9serv\u00e9 \u00e0 la consultation est organis\u00e9 et choisi.<br >Cette restriction n\u2019est \u00e9videmment pas valable en cas de v\u00e9ritable urgence comme un tr\u00e8s jeune enfant fi\u00e9vreux ou encore une r\u00e9action allergique \u00e0 une piqure d\u2019insecte\u2026 Motifs qui peuvent justifier qu\u2019on bouleverse un agenda.<br >Un mal de dos, une toux qui traine, un nez qui coule, la d\u00e9livrance d\u2019un document (administratif ou non, arr\u00eat-maladie) ne sont pas des urgences.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n<div  class=\"col-sm-6\">\n<div  class=\"card row-card bordered y-move\">\n<div  class=\"row\">\n<div  class=\"col-sm-fit icon-column\"> <i  class=\"fa icon fa-codepen round bordered color2\"><\/i> <\/div>\n<div  class=\"col-sm\" data-type=\"column\">\n<h5  class=\"color2\">1 rendez-vous = 1 personne<\/h5>\n<p  class=\"\">Par la force des choses, les rendez-vous se font toutes les 15 minutes. Il est facile de comprendre, dans ces conditions, que voir 2 ou 3 personnes en \u00bc d\u2019heure, n\u2019est pas s\u00e9rieux.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n<div  class=\"col-sm-6\">\n<div  class=\"card row-card bordered y-move\">\n<div  class=\"row\">\n<div  class=\"col-sm-fit icon-column\"> <i  class=\"fa icon fa-cube round bordered color2\"><\/i> <\/div>\n<div  class=\"col-sm\" data-type=\"column\">\n<h5  class=\"color2\">N\u2019attendez pas le dernier moment pour prendre rendez-vous !<\/h5>\n<p  class=\"\">La plupart du temps, il ne reste plus de place pour le jour m\u00eame.<br >\u00ab Vite fait \u00bb, \u00ab entre 2 rendez-vous \u00bb : cette exigence souvent demand\u00e9e est en contradiction totale avec la pratique de la m\u00e9decine qui par d\u00e9finition demande du temps et ne peut \u00eatre b\u00e2cl\u00e9e.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n<div  class=\"col-sm-6\">\n<div  class=\"card row-card bordered y-move\">\n<div  class=\"row\">\n<div  class=\"col-sm-fit icon-column\"> <i  class=\"fa icon fa-database round bordered color2\"><\/i> <\/div>\n<div  class=\"col-sm\" data-type=\"column\">\n<h5  class=\"color2\">Les rendez-vous non honor\u00e9s non excus\u00e9s ne seront pas renouvel\u00e9s<\/h5>\n<p  class=\"\">Alors que des rendez-vous sont r\u00e9guli\u00e8rement refus\u00e9s faute de place, il arrive que des personnes ne se rendent pas \u00e0 leur consultation sans pr\u00e9venir et sans s\u2019excuser. Ces personnes ne pourront plus prendre rendez-vous au cabinet.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<div  id=\"permis\" style=\"background-color: #ffffff;\" data-label=\"Permis\" data-id=\"content-3\" data-export-id=\"content-3\" data-category=\"content\" class=\"content-3 content-section content-section-spacing\">\n<div  class=\"gridContainer\">\n<div  class=\"row middle-xs\">\n<div  class=\"col-sm-7 full-col-left-padding full-col-right-padding\">\n<div  class=\"row\">\n<div  data-type=\"column\" class=\"space-bottom-small content-title-col\">\n<h5  class=\"\">\n<br >Visites m\u00e9dicales d\u2019aptitude au permis de conduire<\/p>\n<p>pour les d\u00e9partements de l\u2019is\u00e8re (38), du Rh\u00f4ne (69) et la Savoie (73)<\/p>\n<p>Votre m\u00e9decin traitant ne peut r\u00e9aliser cette consultation m\u00eame si il figure sur la liste. <\/h5>\n<\/p><\/div>\n<\/p><\/div>\n<div  class=\"row spaced-cols\" data-type=\"row\">\n<div  class=\"col-xs-6\" data-type=\"column\">\n<h5  class=\"\">\n<br >Documents \u00e0 apporter<\/h5>\n<p  class=\"\">\u2013 le Cerfa \u00ab Avis m\u00e9dical \u2013 Permis de conduire \u00bb,<\/p>\n<p>\u2013 votre permis de conduire ou une copie<\/p>\n<p>\u2013 le questionnaire m\u00e9dical rempli (2 pages)<\/p>\n<p>\u2013 une photo d\u2019identit\u00e9 num\u00e9ris\u00e9e si possible<\/p>\n<p>\u2013 si la visite est li\u00e9e \u00e0 votre \u00e9tat de sant\u00e9, veuillez amener votre dossier m\u00e9dical (ordonnance, courrier d\u2019hospitalisation, r\u00e9sultat de prise de sang, etc\u2026),<\/p>\n<p>\u2013 un r\u00e8glement en ch\u00e8que ou esp\u00e8ces ou CB de 40\u20ac<\/p>\n<p  class=\"\">Vous \u00eates concern\u00e9 :<\/p>\n<p> \u2013 si vous \u00eates candidat ou avez besoin de renouveler un permis cat\u00e9gories C, C1, CE, C1E, D, D1, DE et D1E.<\/p>\n<p>\u2013 si<br \/>\nvous souhaitez exercer l\u2019activit\u00e9 de chauffeur de taxi, de conducteur<br \/>\nd\u2019ambulance, de conducteur affect\u00e9 au ramassage scolaire ou au transport<br \/>\n public de personnes, d\u2019enseignant de la conduite ou renouveler cette<br \/>\nautorisation ;<\/p>\n<p> \u2013 si<br \/>\nvous \u00eates atteint d\u2019une affection m\u00e9dicale ou d\u2019un handicap qui<br \/>\nn\u00e9cessite un avis m\u00e9dical avant l\u2019apprentissage de la conduite, le<br \/>\nrenouvellement de votre droit \u00e0 conduire ou un retour \u00e0 la conduite<br \/>\napr\u00e8s une telle affection ;<\/p>\n<p>\u2013 si votre permis est suspendu pour une<br \/>\ndur\u00e9e sup\u00e9rieure \u00e0 un mois ou annul\u00e9 sans infraction li\u00e9e \u00e0 la<br \/>\nconsommation d\u2019alcool et\/ou de stup\u00e9fiants. <\/p>\n<p>Pour<br \/>\n toute infraction li\u00e9e \u00e0 la consommation d\u2019alcool et\/ou de stup\u00e9fiants,<br \/>\nvous devrez passer en commission m\u00e9dicale \u00e0 la pr\u00e9fecture.<\/p>\n<\/div>\n<div  class=\"col-xs-6\" data-type=\"column\"><a  class=\"button blue\" href=\"https:\/\/www.keldoc.com\/medecin-generaliste\/biol-38690\/alban-pouchelon?agenda=7843&amp;motive=23312&amp;category=-1&amp;cabinet=7211\" target=\"_blank\" data-cp-link=\"1\" rel=\"noopener noreferrer\">Prendre RDV pour une visite d\u2019aptitude<\/a> <\/p>\n<h5  class=\"\">T\u00e9l\u00e9chargements<\/h5>\n<p><a  class=\"button blue\" href=\"https:\/\/www.service-public.fr\/particuliers\/vosdroits\/R14006\" target=\"_blank\" data-cp-link=\"1\" rel=\"noopener noreferrer\">Cerfa permis de conduire \u2013 Avis m\u00e9dical \u2013 n\u00b014880*02<\/a><a  class=\"button blue\" href=\"https:\/\/www.bas-rhin.gouv.fr\/contenu\/telechargement\/51885\/378788\/file\/QUESTIONNAIRE%20MEDICAL.pdf\" target=\"_blank\" data-cp-link=\"1\" rel=\"noopener noreferrer\">Questionnaire m\u00e9dical<\/a><a  class=\"button blue\" href=\"https:\/\/permisdeconduire.ants.gouv.fr\/Services-associes\/Ou-faire-ma-photo-et-ma-signature-numerisee\" target=\"_blank\" data-cp-link=\"1\" rel=\"noopener noreferrer\">O\u00f9 faire ma photo num\u00e9ris\u00e9e<\/a><\/div>\n<\/p><\/div>\n<\/div>\n<div  class=\"col-sm-5 bg-image shadow-large-black revert-classes-holder\" data-bg=\"image\" style=\"background-image: url(&quot;https:\/\/alban-pouchelon.fr\/wp-content\/uploads\/2020\/01\/cropped-key-791390_1920.jpg&quot;);\"><\/div>\n<\/div><\/div>\n<\/div>\n<div  id=\"liens-utiles\" style=\"background-color: #ffffff;\" data-label=\"Liens utiles\" data-id=\"team-2\" data-export-id=\"team-2\" data-category=\"team\" class=\"team-2 content-section content-section-spacing\">\n<div  class=\"gridContainer\">\n<div  class=\"row text-center\">\n<div  class=\"section-title-col\" data-type=\"column\">\n<h2  class=\"\">Liens utiles<\/h2>\n<p  class=\"lead\">en cas d\u2019annulation du permis (solde nul) ou en cas de suspension de 6 mois, vous devez aussi passer des tests psychotechniques. Voici la listes des centres (sous r\u00e9serve de mise \u00e0 jour) , ainsi que d\u2019autres liens utiles<\/p>\n<\/div><\/div>\n<div  class=\"row spaced-cols content-center-sm\" data-type=\"row\">\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"> <img  decoding=\"async\" loading=\"lazy\" class=\"face\" src=\"https:\/\/i2.wp.com\/alban-pouchelon.fr\/wp-content\/uploads\/2020\/01\/cropped-cropped-board-361516_1920-1.jpg?w=3840&amp;ssl=1\" alt=\"\" title=\"cropped-cropped-board-361516_1920-1.jpg\" width=\"223\" height=\"223\"> <\/p>\n<div  data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\">\n<h4  class=\"font-500\">Tests psychotechniques 38<\/h4>\n<p>   <a  class=\"button blue\" href=\"https:\/\/www.httpshttps:\/\/www.isere.gouv.fr\/Demarches\/Permis-de-conduire-routiers\/Documents-pour-vos-demarches:\/\/www.isere.gouv.fr\/contenu\/telechargement\/59169\/394664\/version\/1\/file\/2021+11+liste+des+organismes+et+psychologues+d%C3%A9clar%C3%A9s+pour+faire+passer+des+tests+psychotechniques.pdfisere.gouv.fr\/Accueil-sur-rendez-vous\/Prendre-rendez-vous2\/Arrondissement-de-La-Tour-du-Pin\" target=\"_blank\" data-cp-link=\"1\" rel=\"noopener noreferrer\">Liste<\/a><\/p>\n<div  class=\"social-icons-group\" data-type=\"group\"> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-facebook-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-twitter-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-linkedin-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-google-plus-square\"><\/i><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"> <img  decoding=\"async\" loading=\"lazy\" class=\"face\" src=\"https:\/\/i2.wp.com\/alban-pouchelon.fr\/wp-content\/uploads\/2020\/01\/cropped-cropped-checklist-1622517_1920.png?w=3840&amp;ssl=1\" alt=\"\" title=\"cropped-cropped-checklist-1622517_1920.png\" width=\"223\" height=\"223\"> <\/p>\n<div  data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\">\n<h4  class=\"font-500\">Tests psychotechniques 69<\/h4>\n<p>   <a  class=\"button blue\" href=\"http:\/\/www.rhone.gouv.fr\/Demarches-administratives\/Permis-de-conduire-routier\/Passer-l-examen-du-permis-de-conduire-dans-le-Rhone\/Retour-au-permis-apres-invalidation-ou-annulation-du-permis\/3-Tests-psychotechniques-et-visite-medicale-aupres-d-un-medecin-agree-ou-de-la-commission-medicale\" target=\"_blank\" data-cp-link=\"1\" rel=\"noopener noreferrer\">Liste<\/a><\/p>\n<div  class=\"social-icons-group\" data-type=\"group\"> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-facebook-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-twitter-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-linkedin-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-google-plus-square\"><\/i><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"> <img  decoding=\"async\" loading=\"lazy\" class=\"face\" src=\"https:\/\/i2.wp.com\/alban-pouchelon.fr\/wp-content\/uploads\/2020\/01\/cropped-list-2389219_1280.png?w=3840&amp;ssl=1\" alt=\"\" title=\"cropped-list-2389219_1280\" width=\"223\" height=\"223\"> <\/p>\n<div  data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\">\n<h4  class=\"font-500\">Tests psychotechniques 73<\/h4>\n<p>   <a  class=\"button blue\" href=\"http:\/\/www.rhone.gouv.fr\/Demarches-administratives\/Permis-de-conduire-routier\/Passer-l-examen-du-permis-de-conduire-dans-le-Rhone\/Retour-au-permis-apres-invalidation-ou-annulation-du-permis\/3-Tests-psychotechniques-et-visite-medicale-aupres-d-un-medecin-agree-ou-de-la-commission-medicale\" target=\"_blank\" data-cp-link=\"1\" rel=\"noopener noreferrer\">Liste (\u00e0 droite de la page)<\/a><\/p>\n<div  class=\"social-icons-group\" data-type=\"group\"> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-facebook-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-twitter-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-linkedin-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-google-plus-square\"><\/i><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"> <img  decoding=\"async\" loading=\"lazy\" class=\"face\" src=\"https:\/\/i1.wp.com\/alban-pouchelon.fr\/wp-content\/uploads\/2020\/01\/cropped-office-1209640_1920-1.jpg?w=3840&amp;ssl=1\" alt=\"\" title=\"cropped-office-1209640_1920\" width=\"223\" height=\"223\"> <\/p>\n<div  data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\">\n<h4  class=\"font-500\">D\u00e9roulement des tests<\/h4>\n<p>   <a  class=\"button blue\" href=\"https:\/\/www.youtube.com\/watch?v=sFMxcYd-l7c\" target=\"_blank\" data-cp-link=\"1\" rel=\"noopener noreferrer\">Vid\u00e9o explicative<\/a><\/p>\n<div  class=\"social-icons-group\" data-type=\"group\"> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-facebook-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-twitter-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-linkedin-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-google-plus-square\"><\/i><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"> <img  decoding=\"async\" loading=\"lazy\" class=\"face\" src=\"https:\/\/i0.wp.com\/alban-pouchelon.fr\/wp-content\/uploads\/2020\/01\/cropped-cropped-Blason_dpartement_fr_Isre_002.png?w=3840&amp;ssl=1\" alt=\"\" title=\"cropped-cropped-Blason_dpartement_fr_Isre_002.png\" width=\"223\" height=\"223\"> <\/p>\n<div  data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\">\n<h4  class=\"font-500\">Commission m\u00e9dicale 38<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Lien pour prise RDV \u00e0 la Sous Pr\u00e9fecture de La Tour du Pin<\/p>\n<p>  <a  class=\"button blue\" href=\"https:\/\/www.isere.gouv.fr\/Accueil-sur-rendez-vous\/Prendre-rendez-vous2\/Arrondissement-de-La-Tour-du-Pin\" target=\"_blank\" data-cp-link=\"1\" rel=\"noopener noreferrer\">Lien<\/a><\/p>\n<div  class=\"social-icons-group\" data-type=\"group\"> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-facebook-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-twitter-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-linkedin-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-google-plus-square\"><\/i><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"> <img  decoding=\"async\" loading=\"lazy\" class=\"face\" src=\"https:\/\/i0.wp.com\/alban-pouchelon.fr\/wp-content\/uploads\/2020\/01\/cropped-Blason_dpartement_fr_Isre.png?w=3840&amp;ssl=1\" alt=\"\" title=\"cropped-Blason_dpartement_fr_Isre\" width=\"223\" height=\"223\"> <\/p>\n<div  data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\">\n<h4  class=\"font-500\">Commission m\u00e9dicale 38<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Lien pour prise RDV \u00e0 la Pr\u00e9fecture de Grenoble\n<\/p>\n<p>  <a  class=\"button blue\" href=\"https:\/\/www.isere.gouv.fr\/Accueil-sur-rendez-vous\/Prendre-rendez-vous2\/Arrondissement-de-La-Tour-du-Pin\" target=\"_blank\" data-cp-link=\"1\" rel=\"noopener noreferrer\">Lien<\/a><\/p>\n<div  class=\"social-icons-group\" data-type=\"group\"> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-facebook-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-twitter-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-linkedin-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-google-plus-square\"><\/i><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"> <img  decoding=\"async\" loading=\"lazy\" class=\"face\" src=\"https:\/\/i1.wp.com\/alban-pouchelon.fr\/wp-content\/uploads\/2020\/01\/cropped-1024px-Blason_duche_fr_Savoie.png?w=3840&amp;ssl=1\" alt=\"\" title=\"cropped-1024px-Blason_duche_fr_Savoie\" width=\"223\" height=\"222\"> <\/p>\n<div  data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\">\n<h4  class=\"font-500\">Commission m\u00e9dicale 73<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Lien pour prise RDV \u00e0 la  Pr\u00e9fecture de Chambery\n<\/p>\n<p> <a  class=\"button blue\" href=\"https:\/\/www.savoie.gouv.fr\/Prendre-rendez-vous-en-ligne\" target=\"_blank\" data-cp-link=\"1\" rel=\"noopener noreferrer\">Lien<\/a><\/p>\n<div  class=\"social-icons-group\" data-type=\"group\"> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-facebook-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-twitter-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-linkedin-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-google-plus-square\"><\/i><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"> <img  decoding=\"async\" loading=\"lazy\" class=\"face\" src=\"https:\/\/i0.wp.com\/alban-pouchelon.fr\/wp-content\/uploads\/2020\/01\/cropped-Blason_dpartement_fr_Rhne.png?w=3840&amp;ssl=1\" alt=\"\" title=\"cropped-Blason_dpartement_fr_Rhne\" width=\"223\" height=\"223\"> <\/p>\n<div  data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\">\n<h4  class=\"font-500\">Commission m\u00e9dicale 69<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Lien pour prise RDV \u00e0 la Pr\u00e9fecture de Lyon\n<\/p>\n<p>  <a  class=\"button blue\" href=\"http:\/\/www.rhone.gouv.fr\/Demarches-administratives\/Permis-de-conduire-routier\/Visite-medicale\/Commissions-medicales-de-Lyon-et-de-Villefranche-sur-Saone\/Lyon\" target=\"_blank\" data-cp-link=\"1\" rel=\"noopener noreferrer\">Lien<\/a><\/p>\n<div  class=\"social-icons-group\" data-type=\"group\"> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-facebook-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-twitter-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-linkedin-square\"><\/i><\/a> <a  href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener noreferrer\"><i  class=\"gray fa icon fa-google-plus-square\"><\/i><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<div  id=\"blog\" style=\"background-color: #f5fafd;\" data-label=\"Blog\" data-id=\"blog-section\" data-export-id=\"blog-section\" data-category=\"latest_news\" class=\"blog-section blog-section-standard content-section content-section-spacing\">\n<div  class=\"gridContainer\">\n<div  class=\"row\">\n<div  data-type=\"column\" class=\"section-title-col\">\n<h2  class=\"\">Derni\u00e8res nouvelles<\/h2>\n<p  class=\"lead\">Les news \u2026.<\/p>\n<\/div><\/div>\n<div  class=\"row\">\n<div  data-type=\"row\" data-dynamic-columns=\"handled\" data-content-shortcode=\"mesmerize_latest_news\">[mesmerize_latest_news]<\/div>\n<\/div>\n<div  class=\"row\">\n<div  class=\"text-center\"> <a  class=\"button color1\" data-attr-shortcode=\"href:mesmerize_blog_link\" href=\"[mesmerize_blog_link]\">SEE ALL BLOG POSTS<\/a><\/div>\n<\/p><\/div>\n<\/div>\n<\/div>\n<div  data-label=\"About\" data-id=\"about--2\" data-export-id=\"about-4\" data-category=\"about\" class=\"about-4 content-section content-section-spacing\" id=\"about-2\" style=\"background-color: rgb(255, 255, 255);\">\n<div  class=\"gridContainer\">\n<div  class=\"row middle-sm text-center\">\n<div  class=\"col-sm-5 space-bottom-xs\" data-type=\"column\">\n<h2  class=\"\">Mentions l\u00e9gales<span  style=\"font-family: Playfair Display,sans-serif; font-weight: 700; font-style: italic;\" href=\"#\"><\/span><\/h2>\n<p>  <a  class=\"button color1\" href=\"https:\/\/alban-pouchelon.fr\/index.php\/mentionslegales\" target=\"_self\" data-cp-link=\"1\" rel=\"noopener noreferrer\">ici<\/a><\/div>\n<div  class=\"col-sm-7 flexbox center-xs middle-xs image-group-2-img\"> <img  decoding=\"async\" loading=\"lazy\" class=\"img-1 shadow-large\" data-size=\"250x200\" src=\"https:\/\/i0.wp.com\/alban-pouchelon.fr\/wp-content\/plugins\/mesmerize-companion\/theme-data\/mesmerize\/sections\/images\/apple-1838564.jpg?w=3840&amp;ssl=1\" width=\"336\" height=\"224\"> <img  decoding=\"async\" loading=\"lazy\" class=\"img-2 shadow-large\" data-size=\"220x170\" src=\"https:\/\/i1.wp.com\/alban-pouchelon.fr\/wp-content\/plugins\/mesmerize-companion\/theme-data\/mesmerize\/sections\/images\/computer-2569652.jpg?w=3840&amp;ssl=1\" width=\"336\" height=\"224\"><\/div>\n<\/p><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le cabinet Pr\u00e9sentation du cabinet, localisation , fonctionnement Visite m\u00e9dicale permis de conduire Informations diverses pour les consultations d\u2019aptitude au permis de conduire, hors comission m\u00e9dicale Infos pratiques Horaires du cabinet, urgences Liens utiles Divers liens et adresses \u2026 Maison m\u00e9dicale de Biol situ\u00e9e au 9 place Saint Jean Baptiste 38690 BIOL Acc\u00e8s handicap\u00e9 et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/homepage.php","meta":{"footnotes":""},"class_list":["post-5","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/alban-pouchelon.fr\/index.php\/wp-json\/wp\/v2\/pages\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alban-pouchelon.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alban-pouchelon.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alban-pouchelon.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alban-pouchelon.fr\/index.php\/wp-json\/wp\/v2\/comments?post=5"}],"version-history":[{"count":61,"href":"https:\/\/alban-pouchelon.fr\/index.php\/wp-json\/wp\/v2\/pages\/5\/revisions"}],"predecessor-version":[{"id":478,"href":"https:\/\/alban-pouchelon.fr\/index.php\/wp-json\/wp\/v2\/pages\/5\/revisions\/478"}],"wp:attachment":[{"href":"https:\/\/alban-pouchelon.fr\/index.php\/wp-json\/wp\/v2\/media?parent=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}